{"id":678,"count":20,"description":"","link":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/","name":"Gig bags","slug":"gig-bags-brass-accessories","taxonomy":"product_cat","parent":443,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gig bags Archives - Trevor Jones Brass &amp; Woodwind<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gig bags Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"Trevor Jones Brass &amp; Woodwind\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/product-category\\\/brass-accessories\\\/gig-bags-brass-accessories\\\/\",\"url\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/product-category\\\/brass-accessories\\\/gig-bags-brass-accessories\\\/\",\"name\":\"Gig bags Archives - Trevor Jones Brass &amp; Woodwind\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/product-category\\\/brass-accessories\\\/gig-bags-brass-accessories\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/product-category\\\/brass-accessories\\\/gig-bags-brass-accessories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brass Accessories\",\"item\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/product-category\\\/brass-accessories\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gig bags\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#website\",\"url\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/\",\"name\":\"Trevor Jones Brass &amp; Woodwind\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#organization\",\"name\":\"TREVOR JONES BRASS & WOODWIND LTD\",\"url\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/trevorjonesltd.co.uk\\\/shop\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo31.jpg?fit=160%2C75&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/trevorjonesltd.co.uk\\\/shop\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo31.jpg?fit=160%2C75&ssl=1\",\"width\":160,\"height\":75,\"caption\":\"TREVOR JONES BRASS & WOODWIND LTD\"},\"image\":{\"@id\":\"https:\\\/\\\/trevorjonesltd.co.uk\\\/shop\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gig bags Archives - Trevor Jones Brass &amp; Woodwind","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/","og_locale":"en_GB","og_type":"article","og_title":"Gig bags Archives","og_url":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/","og_site_name":"Trevor Jones Brass &amp; Woodwind","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/","url":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/","name":"Gig bags Archives - Trevor Jones Brass &amp; Woodwind","isPartOf":{"@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#website"},"breadcrumb":{"@id":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/gig-bags-brass-accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trevorjonesltd.co.uk\/shop\/"},{"@type":"ListItem","position":2,"name":"Brass Accessories","item":"https:\/\/trevorjonesltd.co.uk\/shop\/product-category\/brass-accessories\/"},{"@type":"ListItem","position":3,"name":"Gig bags"}]},{"@type":"WebSite","@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#website","url":"https:\/\/trevorjonesltd.co.uk\/shop\/","name":"Trevor Jones Brass &amp; Woodwind","description":"","publisher":{"@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trevorjonesltd.co.uk\/shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#organization","name":"TREVOR JONES BRASS & WOODWIND LTD","url":"https:\/\/trevorjonesltd.co.uk\/shop\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/trevorjonesltd.co.uk\/shop\/wp-content\/uploads\/2019\/10\/logo31.jpg?fit=160%2C75&ssl=1","contentUrl":"https:\/\/i1.wp.com\/trevorjonesltd.co.uk\/shop\/wp-content\/uploads\/2019\/10\/logo31.jpg?fit=160%2C75&ssl=1","width":160,"height":75,"caption":"TREVOR JONES BRASS & WOODWIND LTD"},"image":{"@id":"https:\/\/trevorjonesltd.co.uk\/shop\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/trevorjonesltd.co.uk\/shop\/wp-json\/wp\/v2\/product_cat\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trevorjonesltd.co.uk\/shop\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/trevorjonesltd.co.uk\/shop\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/trevorjonesltd.co.uk\/shop\/wp-json\/wp\/v2\/product_cat\/443"}],"wp:post_type":[{"href":"https:\/\/trevorjonesltd.co.uk\/shop\/wp-json\/wp\/v2\/product?product_cat=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}